{"id":11384,"date":"2025-11-24T20:52:25","date_gmt":"2025-11-25T02:52:25","guid":{"rendered":"https:\/\/realidadturistica.com\/realtur\/?p=11384"},"modified":"2025-11-24T21:16:27","modified_gmt":"2025-11-25T03:16:27","slug":"merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral","status":"publish","type":"post","link":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/","title":{"rendered":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral"},"content":{"rendered":"\n<p class=\"wp-block-yoast-seo-estimated-reading-time yoast-reading-time__wrapper\"><span class=\"yoast-reading-time__icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-icon=\"clock\" width=\"20\" height=\"20\" fill=\"none\" stroke=\"currentColor\" style=\"display:inline-block;vertical-align:-0.1em\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M12 8v4l3 3m6-3a9 9 0 11-18 0 9 9 0 0118 0z\"><\/path><\/svg><\/span><span class=\"yoast-reading-time__spacer\" style=\"display:inline-block;width:1em\"><\/span><span class=\"yoast-reading-time__descriptive-text\">Estimated reading time: <\/span><span class=\"yoast-reading-time__reading-time\">3<\/span><span class=\"yoast-reading-time__time-unit\"> minutos<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal Alejandro Paz Noriega, subsecretario de Desarrollo Tur\u00edstico Sustentable de la Secretar\u00eda de Fomento Tur\u00edstico (SEFOTUR), se realiz\u00f3 en el Centro Internacional de Congresos de Yucat\u00e1n este lunes 24 de noviembre el lanzamiento del Sexto Congreso Internacional de Maestros Chefs de Cocina Ancestral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este importante encuentro culinario, que se llevar\u00e1 a cabo los d\u00edas 28 y 29 de noviembre en el Centro de Convenciones Siglo XXI, contar\u00e1 con la presencia de maestros de cocina de Cuba, Per\u00fa, El Salvador, Estados Unidos, Nicaragua, Brasil, Colombia, Argentina y M\u00e9xico. Tambi\u00e9n participar\u00e1n cocineros tradicionales mexicanos de Tabasco, Campeche, Guerrero, Chiapas y Yucat\u00e1n, entre otros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1024x576.jpg\" alt=\"\" class=\"wp-image-11386\" srcset=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1024x576.jpg 1024w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-300x169.jpg 300w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-768x432.jpg 768w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1536x864.jpg 1536w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-2048x1152.jpg 2048w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1920x1080.jpg 1920w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1170x658.jpg 1170w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-585x329.jpg 585w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124111236-1200x675.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Chef Pedro Jos\u00e9 Estrada V\u00e1zquez al hacer uso de la palabra reiter\u00f3 la importancia de este encuentro que busca mantener viva la cocina tradicional yucateca, remont\u00e1ndose a nuestros ancestros, una cultura que se debe de preservar en las nuevas generaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte Paz Noriega de Sofotur, resalt\u00f3 la fortaleza de este tipo de espacios para el desarrollo del turismo, pues se buscan conjugar las ra\u00edces culinarias del estado con las t\u00e9cnicas modernas de la preparaci\u00f3n de alimentos. Destac\u00f3 que Yucat\u00e1n fue galardonada en la reci\u00e9n finalizada Feria Internacional de Turismo (FITUR), en Madrid, Espa\u00f1a, como la Capital Iberoamericana de la Cultura Gastron\u00f3mica 2025, t\u00edtulo que llena de orgullo a Yucat\u00e1n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1024x576.jpg\" alt=\"\" class=\"wp-image-11387\" srcset=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1024x576.jpg 1024w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-300x169.jpg 300w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-768x432.jpg 768w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1536x864.jpg 1536w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-2048x1152.jpg 2048w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1920x1080.jpg 1920w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1170x658.jpg 1170w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-585x329.jpg 585w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110644-1200x675.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de este importante encuentro los chefs visitantes impartir\u00e1n clases magistrales y sostendr\u00e1n encuentros con cocineros tradicionales del estado, adem\u00e1s de realizar un recorrido por zonas de inter\u00e9s hist\u00f3rico de Yucat\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 el Chef Pedro Jos\u00e9 Estrada V\u00e1zquez que la Universidad Tecnol\u00f3gica de Calakmul de Campeche firmar\u00e1 un convenio con la Federaci\u00f3n Culinaria de Cuba para realizar un intercambio entre chefs de M\u00e9xico y Cuba, con vistas a preparar a maestros de cocina en las tradiciones culinarias de ambos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estuvieron presentes en el lanzamiento Karla Sol\u00eds Moreno, defensora de la Cocina Ancestral y organizadora del evento, Alejandra Ortiz Flores, propietaria de Acozac Frutas y Semillas, el sommelier Jos\u00e9 Carlos Palacio, prensa especializada y un grupo de emprendedores amantes de la cocina ancestral.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"11388\" src=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1024x576.jpg\" alt=\"\" class=\"wp-image-11388\" srcset=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1024x576.jpg 1024w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-300x169.jpg 300w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-768x432.jpg 768w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1536x864.jpg 1536w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-2048x1152.jpg 2048w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1920x1080.jpg 1920w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1170x658.jpg 1170w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-585x329.jpg 585w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110603-1200x675.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"11389\" src=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1024x576.jpg\" alt=\"\" class=\"wp-image-11389\" srcset=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1024x576.jpg 1024w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-300x169.jpg 300w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-768x432.jpg 768w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1536x864.jpg 1536w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-2048x1152.jpg 2048w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1920x1080.jpg 1920w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1170x658.jpg 1170w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-585x329.jpg 585w, https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124110631-1200x675.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar la conferencia de prensa los participantes degustaron algunos de los platos t\u00edpicos tradiciones que estar\u00e1n expuestos durante la jornada gastron\u00f3mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrada ser\u00e1 libre y cumplir\u00e1 un ambicioso programa que ser\u00e1 del agrado de todos los visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Realidad Tur\u00edstica<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Sexto Congreso Internacional de Maestros Chefs de Cocina Ancestral.\" width=\"563\" height=\"1000\" src=\"https:\/\/www.youtube.com\/embed\/QArPpp9s7CE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal Alejandro Paz Noriega, subsecretario de Desarrollo&hellip;<\/p>\n","protected":false},"author":2,"featured_media":11385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-11384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica<\/title>\n<meta name=\"description\" content=\"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/\" \/>\n<meta property=\"og:site_name\" content=\"Realidad Tur\u00edstica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realidadturistica\" \/>\n<meta property=\"article:author\" content=\"profile.php?id=61576165411521\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T02:52:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-25T03:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuel Lorenzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Lorenzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/\"},\"author\":{\"name\":\"Manuel Lorenzo\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\"},\"headline\":\"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral\",\"datePublished\":\"2025-11-25T02:52:25+00:00\",\"dateModified\":\"2025-11-25T03:16:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/\"},\"wordCount\":457,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG20251124113230-scaled.jpg\",\"articleSection\":[\"Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/\",\"name\":\"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG20251124113230-scaled.jpg\",\"datePublished\":\"2025-11-25T02:52:25+00:00\",\"dateModified\":\"2025-11-25T03:16:27+00:00\",\"description\":\"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG20251124113230-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG20251124113230-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"name\":\"Realidad Tur\u00edstica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\",\"name\":\"Realidad Tur\u00edstica\",\"alternateName\":\"Realtur\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"width\":1382,\"height\":629,\"caption\":\"Realidad Tur\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realidadturistica\",\"https:\\\/\\\/www.instagram.com\\\/realidad_turistica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\",\"name\":\"Manuel Lorenzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"caption\":\"Manuel Lorenzo\"},\"description\":\"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.\",\"sameAs\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"profile.php?id=61576165411521\"],\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/author\\\/editor2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica","description":"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica","og_description":"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal","og_url":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/","og_site_name":"Realidad Tur\u00edstica","article_publisher":"https:\/\/www.facebook.com\/realidadturistica","article_author":"profile.php?id=61576165411521","article_published_time":"2025-11-25T02:52:25+00:00","article_modified_time":"2025-11-25T03:16:27+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg","type":"image\/jpeg"}],"author":"Manuel Lorenzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Manuel Lorenzo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#article","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/"},"author":{"name":"Manuel Lorenzo","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c"},"headline":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral","datePublished":"2025-11-25T02:52:25+00:00","dateModified":"2025-11-25T03:16:27+00:00","mainEntityOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/"},"wordCount":457,"commentCount":0,"publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg","articleSection":["Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/","url":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/","name":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral - Realidad Tur\u00edstica","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#primaryimage"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg","datePublished":"2025-11-25T02:52:25+00:00","dateModified":"2025-11-25T03:16:27+00:00","description":"Estimated reading time: 3 minutos M\u00e9xico. Con la presencia del Chef Pedro Jos\u00e9 Estrada V\u00e1zquez, embajador y promotor de las cocinas ancestrales, y Ra\u00fal","breadcrumb":{"@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#primaryimage","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2025\/11\/IMG20251124113230-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/realidadturistica.com\/realtur\/merida-sera-sede-del-congreso-internacional-de-maestros-chefs-de-cocina-ancestral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/realidadturistica.com\/realtur\/"},{"@type":"ListItem","position":2,"name":"M\u00e9rida ser\u00e1 sede del Congreso Internacional de Maestros Chefs de Cocina Ancestral"}]},{"@type":"WebSite","@id":"https:\/\/realidadturistica.com\/realtur\/#website","url":"https:\/\/realidadturistica.com\/realtur\/","name":"Realidad Tur\u00edstica","description":"","publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realidadturistica.com\/realtur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/realidadturistica.com\/realtur\/#organization","name":"Realidad Tur\u00edstica","alternateName":"Realtur","url":"https:\/\/realidadturistica.com\/realtur\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","width":1382,"height":629,"caption":"Realidad Tur\u00edstica"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realidadturistica","https:\/\/www.instagram.com\/realidad_turistica\/"]},{"@type":"Person","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c","name":"Manuel Lorenzo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","caption":"Manuel Lorenzo"},"description":"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.","sameAs":["https:\/\/realidadturistica.com\/realtur\/","profile.php?id=61576165411521"],"url":"https:\/\/realidadturistica.com\/realtur\/author\/editor2\/"}]}},"_links":{"self":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/11384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/comments?post=11384"}],"version-history":[{"count":2,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/11384\/revisions"}],"predecessor-version":[{"id":11392,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/11384\/revisions\/11392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media\/11385"}],"wp:attachment":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media?parent=11384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/categories?post=11384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/tags?post=11384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}