{"id":5431,"date":"2023-10-04T11:56:46","date_gmt":"2023-10-04T11:56:46","guid":{"rendered":"https:\/\/realidadturistica.com\/realtur\/?p=5431"},"modified":"2023-10-04T12:00:13","modified_gmt":"2023-10-04T12:00:13","slug":"sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad","status":"publish","type":"post","link":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/","title":{"rendered":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0"},"content":{"rendered":"\n<p class=\"yoast-reading-time__wrapper\"><span class=\"yoast-reading-time__icon\"><\/span><span class=\"yoast-reading-time__descriptive-text\">Tiempo de lectura estimado:  <\/span><span class=\"yoast-reading-time__reading-time\">4<\/span><span class=\"yoast-reading-time__time-unit\"> minutos<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas m\u00e1s emblem\u00e1ticos, el Vacaciones Tercera Edad, que desde el a\u00f1o 2001 viene beneficiando a personas mayores a trav\u00e9s del turismo. El evento, denominado Carnaval Mayor, congreg\u00f3 a m\u00e1s de 1.700 personas, quienes llegaron hasta el Parque Mirador Viejo en la comuna de Independencia para conocer las novedades de esta iniciativa de turismo social y tambi\u00e9n disfrutar de gastronom\u00eda, m\u00fasica en vivo, emprendedores y concursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la oportunidad, las autoridades nacionales de turismo dieron a conocer la apertura de 3.500 nuevos cupos para recorrer Chile, los que se suman a los m\u00e1s de 3.000 que ya estaban disponibles. De este modo, se espera alcanzar una cifra superior a las 40.000 personas mayores y sus acompa\u00f1antes que se vean favorecidas hasta el t\u00e9rmino de la actual temporada, en julio de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La subsecretaria de Turismo, Ver\u00f3nica Pardo, manifest\u00f3 que \u201cVacaciones Tercera Edad, que lleva m\u00e1s de veinte a\u00f1os, permite un empuje econ\u00f3mico de las localidades, un desarrollo de los territorios y de las experiencias, adem\u00e1s de la posibilidad de potenciar nuevos destinos. Sin embargo, lo m\u00e1s importante es el efecto que tiene en las personas mayores, quienes reciben un impacto inmediato en su bienestar y salud emocional. Por eso, a petici\u00f3n del presidente Boric, trabajamos a\u00fan m\u00e1s en este programa, generando mayores y mejores alianzas para fortalecer los viajes en este grupo de la poblaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el director nacional de Sernatur, Crist\u00f3bal Ben\u00edtez, \u201cel evento fue todo un \u00e9xito, sobre todo por la articulaci\u00f3n que logramos y tambi\u00e9n porque tomamos espacios p\u00fablicos para desarrollar actividades en un ambiente familiar. Estamos felices por mostrar todas las opciones que tienen las personas mayores para viajar con nuestro programa. Hay alternativas para todos los gustos y bolsillos: viajes de una semana, escapadas de fin de semana y otras experiencias en 52 destinos en todo Chile. Invitamos a que sean parte y conozcan estas alternativas en www.vacacionesterceraedad.cl\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Carnaval Mayor, los asistentes tambi\u00e9n pudieron encontrar informaci\u00f3n de otras instituciones del Estado, como Senama, Sercotec, Conaf, EFE, BancoEstado, ChileAtiende, IPS y la Divisi\u00f3n de Organizaciones Sociales, as\u00ed como conocer variados productos de emprendimientos de Huechuraba, Maip\u00fa, San Joaqu\u00edn y Santiago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conoce las tres modalidades del Vacaciones Tercera Edad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vacaciones Tercer Edad es un programa de viajes que ejecuta Sernatur en todo el pa\u00eds. Entrega un subsidio estatal de entre un 25 y un 75 por ciento del valor total de paquetes tur\u00edsticos especialmente dise\u00f1ados para personas mayores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mayor\u00eda, los paquetes de viaje vienen con todo incluido, pues consideran servicios de alojamiento, alimentaci\u00f3n, traslados terrestres y a\u00e9reos, actividades recreativas, seguro de asistencia en viaje, experiencias y tours dependiendo de su tipo de modalidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas son las modalidades a las que puedes acceder:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Escapadas: viajes con todos los servicios incluidos hacia destinos de la misma regi\u00f3n o regiones contiguas, en transporte terrestre, con hasta un 70 por ciento de subsidio. La duraci\u00f3n de los viajes var\u00eda entre dos o tres noches. Un ejemplo de escapada de tres d\u00edas es de Santiago a Maitencillo (Regi\u00f3n de Valpara\u00edso) a $73.800 y hacia Cobquecura (Regi\u00f3n de \u00d1uble) a $78.275. Las escapadas se compran a trav\u00e9s de agencias de viajes autorizadas, disponibles en www.vacacionesterceraedad.cl\/agencias-de-viajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 VTE Cl\u00e1sico: viajes con todo incluido con una duraci\u00f3n de cuatro a siete noches a destinos en todo el pa\u00eds, mediante viajes a\u00e9reos y terrestres. Tiene, en promedio, un porcentaje de subsidio entre 25 y 75 por ciento, aproximadamente. Ejemplos de viaje de siete noches son de Santiago a La Serena (Regi\u00f3n de Coquimbo) por $351.062, hac\u00edan Valle Las Trancas (Regi\u00f3n de \u00d1uble) por $339.238 y hasta Villarrica (Regi\u00f3n de La Araucan\u00eda) por $363.735. Estos viajes son ofrecidos en agencias de viaje autorizadas y participantes del programa, disponibles en&nbsp; www.vacacionesterceraedad.cl\/agencias-de-viajes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2013 Experiencias Mayores: son viajes personalizables a destinos dobles, en los que se pueden configurar aparte algunos complementos, como almuerzos, cenas y tours. La duraci\u00f3n de los viajes var\u00eda entre las dos o tres noches y tienen un porcentaje de subsidio de hasta un 30 por ciento. Experiencias de siete d\u00edas desde Santiago son las de sol y playa a La Serena-Vicu\u00f1a (Regi\u00f3n de Coquimbo) por $548.000 o de enoturismo y de gastronom\u00eda en Colb\u00fan-Vichuqu\u00e9n (Regi\u00f3n del Maule) por $471.000. Para adquirir estos viajes, basta con ingresar a www.vacacionesterceraedad.cl\/experiencias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: Sernatur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas m\u00e1s emblem\u00e1ticos, el Vacaciones Tercera Edad,&hellip;<\/p>\n","protected":false},"author":2,"featured_media":5432,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-5431","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica<\/title>\n<meta name=\"description\" content=\"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"Realidad Tur\u00edstica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realidadturistica\" \/>\n<meta property=\"article:author\" content=\"profile.php?id=61576165411521\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-04T11:56:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T12:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1159\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuel Lorenzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Lorenzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/\"},\"author\":{\"name\":\"Manuel Lorenzo\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\"},\"headline\":\"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0\",\"datePublished\":\"2023-10-04T11:56:46+00:00\",\"dateModified\":\"2023-10-04T12:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/\"},\"wordCount\":797,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg\",\"articleSection\":[\"Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/\",\"name\":\"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg\",\"datePublished\":\"2023-10-04T11:56:46+00:00\",\"dateModified\":\"2023-10-04T12:00:13+00:00\",\"description\":\"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg\",\"width\":1159,\"height\":494},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"name\":\"Realidad Tur\u00edstica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\",\"name\":\"Realidad Tur\u00edstica\",\"alternateName\":\"Realtur\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"width\":1382,\"height\":629,\"caption\":\"Realidad Tur\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realidadturistica\",\"https:\\\/\\\/www.instagram.com\\\/realidad_turistica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\",\"name\":\"Manuel Lorenzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"caption\":\"Manuel Lorenzo\"},\"description\":\"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.\",\"sameAs\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"profile.php?id=61576165411521\"],\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/author\\\/editor2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica","description":"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/","og_locale":"es_ES","og_type":"article","og_title":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica","og_description":"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas","og_url":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/","og_site_name":"Realidad Tur\u00edstica","article_publisher":"https:\/\/www.facebook.com\/realidadturistica","article_author":"profile.php?id=61576165411521","article_published_time":"2023-10-04T11:56:46+00:00","article_modified_time":"2023-10-04T12:00:13+00:00","og_image":[{"width":1159,"height":494,"url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg","type":"image\/jpeg"}],"author":"Manuel Lorenzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Manuel Lorenzo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#article","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/"},"author":{"name":"Manuel Lorenzo","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c"},"headline":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0","datePublished":"2023-10-04T11:56:46+00:00","dateModified":"2023-10-04T12:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/"},"wordCount":797,"commentCount":0,"publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg","articleSection":["Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/","url":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/","name":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0 - Realidad Tur\u00edstica","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#primaryimage"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg","datePublished":"2023-10-04T11:56:46+00:00","dateModified":"2023-10-04T12:00:13+00:00","description":"Tiempo de lectura estimado: 4 minutos Chile. Con un verdadero carnaval, Sernatur celebr\u00f3 ayer el lanzamiento de la nueva temporada de uno de sus programas","breadcrumb":{"@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#primaryimage","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/10\/Captura-de-pantalla-2023-10-04-a-las-7.53.23-a.m.jpg","width":1159,"height":494},{"@type":"BreadcrumbList","@id":"https:\/\/realidadturistica.com\/realtur\/sernatur-abrio-nuevos-cupos-para-viajar-con-su-programa-vacaciones-tercera-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/realidadturistica.com\/realtur\/"},{"@type":"ListItem","position":2,"name":"Sernatur abri\u00f3 nuevos cupos para viajar con su programa Vacaciones Tercera Edad\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/realidadturistica.com\/realtur\/#website","url":"https:\/\/realidadturistica.com\/realtur\/","name":"Realidad Tur\u00edstica","description":"","publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realidadturistica.com\/realtur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/realidadturistica.com\/realtur\/#organization","name":"Realidad Tur\u00edstica","alternateName":"Realtur","url":"https:\/\/realidadturistica.com\/realtur\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","width":1382,"height":629,"caption":"Realidad Tur\u00edstica"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realidadturistica","https:\/\/www.instagram.com\/realidad_turistica\/"]},{"@type":"Person","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c","name":"Manuel Lorenzo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","caption":"Manuel Lorenzo"},"description":"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.","sameAs":["https:\/\/realidadturistica.com\/realtur\/","profile.php?id=61576165411521"],"url":"https:\/\/realidadturistica.com\/realtur\/author\/editor2\/"}]}},"_links":{"self":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/5431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/comments?post=5431"}],"version-history":[{"count":1,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/5431\/revisions"}],"predecessor-version":[{"id":5433,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/5431\/revisions\/5433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media\/5432"}],"wp:attachment":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media?parent=5431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/categories?post=5431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/tags?post=5431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}