{"id":8201,"date":"2024-10-01T15:57:19","date_gmt":"2024-10-01T15:57:19","guid":{"rendered":"https:\/\/realidadturistica.com\/realtur\/?p=8201"},"modified":"2024-10-01T16:50:11","modified_gmt":"2024-10-01T16:50:11","slug":"enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo","status":"publish","type":"post","link":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/","title":{"rendered":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;<strong><a href=\"https:\/\/enjoytravelgroup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Enjoy Travel Group<\/a><\/strong>&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en S\u00e3o Paulo, como parte de su ambiciosa estrategia de expansi\u00f3n en el mercado latinoamericano y a nivel internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este importante paso refuerza su presencia en la regi\u00f3n, ofreciendo una amplia y variada cartera de productos que abarca desde turismo vacacional, cultural, estudiantil, accesible, MICE, lujo, LGBT, golf y naturaleza, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En paralelo a la apertura de la oficina, Enjoy Travel Group ha tenido una destacada participaci\u00f3n en la prestigiosa feria ABAV Expo, uno de los eventos de turismo m\u00e1s relevantes de Brasil, donde la empresa present\u00f3 sus servicios y fortaleci\u00f3 relaciones con socios comerciales y agencias de viajes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Luis Jim\u00e9nez, vicepresidente de ventas, \u201cLa participaci\u00f3n en ABAV Expo nos ha permitido acercarnos al mercado brasile\u00f1o y presentar nuestra amplia oferta de productos, fortaleciendo la relaci\u00f3n con las agencias locales.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El turoperador tambi\u00e9n se caracteriza por su trabajo constante con agencias de viajes minoristas, desarrollando y capacitando su red de manera continua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cuenta con la potente plataforma B2B&nbsp;<strong>Enjoy Pro<\/strong>, que facilita a los agentes de viajes la gesti\u00f3n y reserva de productos tur\u00edsticos, ofreciendo una herramienta avanzada y eficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con m\u00e1s de 20 a\u00f1os de experiencia,&nbsp;<strong><a href=\"https:\/\/enjoytravelgroup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Enjoy Travel Group<\/a><\/strong>&nbsp;sigue consolid\u00e1ndose como un referente en la industria tur\u00edstica, apostando por la innovaci\u00f3n y la personalizaci\u00f3n en cada uno de sus servicios a nivel global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <strong><a href=\"https:\/\/enjoytravelgroup.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Enjoy Travel Group<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en S\u00e3o Paulo, como parte&hellip;<\/p>\n","protected":false},"author":1,"featured_media":8202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-8201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica<\/title>\n<meta name=\"description\" content=\"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Realidad Tur\u00edstica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realidadturistica\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T15:57:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T16:50:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rt-news2021\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rt-news2021\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/\"},\"author\":{\"name\":\"rt-news2021\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/f5dac4e52586e64466abcd4220a7920b\"},\"headline\":\"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo\",\"datePublished\":\"2024-10-01T15:57:19+00:00\",\"dateModified\":\"2024-10-01T16:50:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/\"},\"wordCount\":286,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/enjoy-sao-paulo.jpeg\",\"articleSection\":[\"Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/\",\"name\":\"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/enjoy-sao-paulo.jpeg\",\"datePublished\":\"2024-10-01T15:57:19+00:00\",\"dateModified\":\"2024-10-01T16:50:11+00:00\",\"description\":\"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/enjoy-sao-paulo.jpeg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/enjoy-sao-paulo.jpeg\",\"width\":1600,\"height\":1200,\"caption\":\"Directivos de Enjoy Travel Group\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"name\":\"Realidad Tur\u00edstica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\",\"name\":\"Realidad Tur\u00edstica\",\"alternateName\":\"Realtur\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"width\":1382,\"height\":629,\"caption\":\"Realidad Tur\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realidadturistica\",\"https:\\\/\\\/www.instagram.com\\\/realidad_turistica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/f5dac4e52586e64466abcd4220a7920b\",\"name\":\"rt-news2021\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-Editor_avatar_1693668634-96x96.png\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-Editor_avatar_1693668634-96x96.png\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/cropped-Editor_avatar_1693668634-96x96.png\",\"caption\":\"rt-news2021\"},\"sameAs\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\"],\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/author\\\/rt-news2021\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica","description":"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/","og_locale":"es_ES","og_type":"article","og_title":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica","og_description":"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en","og_url":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/","og_site_name":"Realidad Tur\u00edstica","article_publisher":"https:\/\/www.facebook.com\/realidadturistica","article_published_time":"2024-10-01T15:57:19+00:00","article_modified_time":"2024-10-01T16:50:11+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg","type":"image\/jpeg"}],"author":"rt-news2021","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"rt-news2021","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#article","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/"},"author":{"name":"rt-news2021","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/f5dac4e52586e64466abcd4220a7920b"},"headline":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo","datePublished":"2024-10-01T15:57:19+00:00","dateModified":"2024-10-01T16:50:11+00:00","mainEntityOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/"},"wordCount":286,"commentCount":0,"publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg","articleSection":["Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/","url":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/","name":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo - Realidad Tur\u00edstica","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#primaryimage"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg","datePublished":"2024-10-01T15:57:19+00:00","dateModified":"2024-10-01T16:50:11+00:00","description":"S\u00e3o Paulo, Brasil \u2013 El turoperador mayorista vertical&nbsp;Enjoy Travel Group&nbsp;ha anunciado la apertura de una nueva oficina en Brasil, localizada en","breadcrumb":{"@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#primaryimage","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/10\/enjoy-sao-paulo.jpeg","width":1600,"height":1200,"caption":"Directivos de Enjoy Travel Group"},{"@type":"BreadcrumbList","@id":"https:\/\/realidadturistica.com\/realtur\/enjoy-travel-group-expande-su-operacion-en-latinoamerica-con-nueva-oficina-en-sao-paulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/realidadturistica.com\/realtur\/"},{"@type":"ListItem","position":2,"name":"Enjoy Travel Group expande su operaci\u00f3n en Latinoam\u00e9rica con nueva oficina en S\u00e3o Paulo"}]},{"@type":"WebSite","@id":"https:\/\/realidadturistica.com\/realtur\/#website","url":"https:\/\/realidadturistica.com\/realtur\/","name":"Realidad Tur\u00edstica","description":"","publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realidadturistica.com\/realtur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/realidadturistica.com\/realtur\/#organization","name":"Realidad Tur\u00edstica","alternateName":"Realtur","url":"https:\/\/realidadturistica.com\/realtur\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","width":1382,"height":629,"caption":"Realidad Tur\u00edstica"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realidadturistica","https:\/\/www.instagram.com\/realidad_turistica\/"]},{"@type":"Person","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/f5dac4e52586e64466abcd4220a7920b","name":"rt-news2021","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/09\/cropped-Editor_avatar_1693668634-96x96.png","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/09\/cropped-Editor_avatar_1693668634-96x96.png","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2023\/09\/cropped-Editor_avatar_1693668634-96x96.png","caption":"rt-news2021"},"sameAs":["https:\/\/realidadturistica.com\/realtur"],"url":"https:\/\/realidadturistica.com\/realtur\/author\/rt-news2021\/"}]}},"_links":{"self":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/comments?post=8201"}],"version-history":[{"count":2,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8201\/revisions"}],"predecessor-version":[{"id":8206,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8201\/revisions\/8206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media\/8202"}],"wp:attachment":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media?parent=8201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/categories?post=8201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/tags?post=8201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}