{"id":8873,"date":"2024-12-29T13:34:01","date_gmt":"2024-12-29T13:34:01","guid":{"rendered":"https:\/\/realidadturistica.com\/realtur\/?p=8873"},"modified":"2024-12-29T13:34:03","modified_gmt":"2024-12-29T13:34:03","slug":"la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa","status":"publish","type":"post","link":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/","title":{"rendered":"La industria tur\u00edstica polaca pisa el acelerador: nace \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-yoast-seo-estimated-reading-time yoast-reading-time__wrapper\"><span class=\"yoast-reading-time__icon\"><svg aria-hidden=\"true\" focusable=\"false\" data-icon=\"clock\" width=\"20\" height=\"20\" fill=\"none\" stroke=\"currentColor\" style=\"display:inline-block;vertical-align:-0.1em\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M12 8v4l3 3m6-3a9 9 0 11-18 0 9 9 0 0118 0z\"><\/path><\/svg><\/span><span class=\"yoast-reading-time__spacer\" style=\"display:inline-block;width:1em\"><\/span><span class=\"yoast-reading-time__descriptive-text\">Estimated reading time: <\/span><span class=\"yoast-reading-time__reading-time\">2<\/span><span class=\"yoast-reading-time__time-unit\"> minutos<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una marca tan emblem\u00e1tica como Thomas Cook, ahora Wirtualna Polska Holding (WP Holding) ha firmado un acuerdo para comprar el 100% de Invia Group, empresa de viajes germana con operaciones en Alemania, Austria, Suiza, Chequia, Eslovaquia, Hungr\u00eda y Polonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El valor de la transacci\u00f3n, pendiente de aprobaci\u00f3n por las autoridades de competencia, es superior a los 240 millones de euros. Entre los principales accionistas de la empresa que vender\u00e1n sus participaciones se encuentran Rockaway Capital y CITIC Europe Holding.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abUna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde WP subrayan que, fruto de la fusi\u00f3n, se crear\u00e1 \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb, con una facturaci\u00f3n conjunta de m\u00e1s de 500 millones de euros, as\u00ed como 3 millones de clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que el holding, que cotiza en la Bolsa de Varsovia desde 2015 y que cuenta con empresas tecnol\u00f3gicas, de comunicaci\u00f3n y de viajes, tendr\u00e1 tres pilares tur\u00edsticos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;-La mayor plataforma de viajes de Polonia (Wakacje.pl), con m\u00e1s de un mill\u00f3n de clientes (Comprada en 2015).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;-Szallas Group, que opera plataformas en Polonia (Nocowanie.pl), Chequia (Hotel.cz, Spa.cz), Hungr\u00eda (Szallas.hu), y Ruman\u00eda (Travelminit.ro, Litoralulromanesc.ro). (Comprado en 2022).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Invia Group, con las plataformas que operan en Alemania, Austria y Suiza (Ab-in-den-Urlaub.de), Polonia (Travelplanet.pl), Chequia (Invia.cz), Slovakia (Invia.sk), y Hungr\u00eda (Invia.hu); as\u00ed como la OTA alemana (Fluege.de).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abQueremos combinar la escala que ofrece el mercado de Europa occidental y el potencial de crecimiento que ofrece el mercado de Europa central y oriental. Para WP Holding, esto tambi\u00e9n representa un cambio de identidad. Por primera vez en nuestra historia, generaremos m\u00e1s ingresos y beneficios de las operaciones de viajes que de los medios de comunicaci\u00f3n\u00bb, ha aseveradosays Jacek \u015awiderski, CEO of WP Holding.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la empresa polaca hacen hincapi\u00e9 en el importante valor del mercado tur\u00edstico europeo, donde Alemania acapara la mayor cuota, suponiendo el 19% del gasto tur\u00edstico total, por lo que consideran clave tener fuerza en la regi\u00f3n DACH.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tourinews.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una marca tan emblem\u00e1tica como Thomas Cook, ahora&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8874,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-8873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La industria tur\u00edstica polaca pisa el acelerador: nace &quot;una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa&quot; - Realidad Tur\u00edstica<\/title>\n<meta name=\"description\" content=\"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La industria tur\u00edstica polaca pisa el acelerador: nace &quot;una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa&quot; - Realidad Tur\u00edstica\" \/>\n<meta property=\"og:description\" content=\"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una\" \/>\n<meta property=\"og:url\" content=\"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Realidad Tur\u00edstica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/realidadturistica\" \/>\n<meta property=\"article:author\" content=\"profile.php?id=61576165411521\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-29T13:34:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-29T13:34:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.png\" \/>\n\t<meta property=\"og:image:width\" content=\"732\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Manuel Lorenzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Lorenzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/\"},\"author\":{\"name\":\"Manuel Lorenzo\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\"},\"headline\":\"La industria tur\u00edstica polaca pisa el acelerador: nace \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb\",\"datePublished\":\"2024-12-29T13:34:01+00:00\",\"dateModified\":\"2024-12-29T13:34:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/\"},\"wordCount\":401,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/La-industria.webp\",\"articleSection\":[\"Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/\",\"name\":\"La industria tur\u00edstica polaca pisa el acelerador: nace \\\"una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\\\" - Realidad Tur\u00edstica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/La-industria.webp\",\"datePublished\":\"2024-12-29T13:34:01+00:00\",\"dateModified\":\"2024-12-29T13:34:03+00:00\",\"description\":\"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/La-industria.webp\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/La-industria.webp\",\"width\":732,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La industria tur\u00edstica polaca pisa el acelerador: nace \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#website\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"name\":\"Realidad Tur\u00edstica\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#organization\",\"name\":\"Realidad Tur\u00edstica\",\"alternateName\":\"Realtur\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logotipo-realidad-turistica.png\",\"width\":1382,\"height\":629,\"caption\":\"Realidad Tur\u00edstica\"},\"image\":{\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/realidadturistica\",\"https:\\\/\\\/www.instagram.com\\\/realidad_turistica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/#\\\/schema\\\/person\\\/46aa3c967b83697123b0ca020fb35e7c\",\"name\":\"Manuel Lorenzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/cropped-manuel-lorenzo-avatar-96x96.jpg\",\"caption\":\"Manuel Lorenzo\"},\"description\":\"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.\",\"sameAs\":[\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/\",\"profile.php?id=61576165411521\"],\"url\":\"https:\\\/\\\/realidadturistica.com\\\/realtur\\\/author\\\/editor2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La industria tur\u00edstica polaca pisa el acelerador: nace \"una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\" - Realidad Tur\u00edstica","description":"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/","og_locale":"es_ES","og_type":"article","og_title":"La industria tur\u00edstica polaca pisa el acelerador: nace \"una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\" - Realidad Tur\u00edstica","og_description":"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una","og_url":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/","og_site_name":"Realidad Tur\u00edstica","article_publisher":"https:\/\/www.facebook.com\/realidadturistica","article_author":"profile.php?id=61576165411521","article_published_time":"2024-12-29T13:34:01+00:00","article_modified_time":"2024-12-29T13:34:03+00:00","og_image":[{"width":732,"height":400,"url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.png","type":"image\/png"}],"author":"Manuel Lorenzo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Manuel Lorenzo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#article","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/"},"author":{"name":"Manuel Lorenzo","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c"},"headline":"La industria tur\u00edstica polaca pisa el acelerador: nace \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb","datePublished":"2024-12-29T13:34:01+00:00","dateModified":"2024-12-29T13:34:03+00:00","mainEntityOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/"},"wordCount":401,"commentCount":0,"publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.webp","articleSection":["Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/","url":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/","name":"La industria tur\u00edstica polaca pisa el acelerador: nace \"una de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\" - Realidad Tur\u00edstica","isPartOf":{"@id":"https:\/\/realidadturistica.com\/realtur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#primaryimage"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.webp","datePublished":"2024-12-29T13:34:01+00:00","dateModified":"2024-12-29T13:34:03+00:00","description":"Estimated reading time: 2 minutos Polonia. La industria tur\u00edstica polaca est\u00e1 pisando fuerte. Si recientemente la agencia de viajes online eSky compr\u00f3 una","breadcrumb":{"@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#primaryimage","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.webp","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2024\/12\/La-industria.webp","width":732,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/realidadturistica.com\/realtur\/la-industria-turistica-polaca-pisa-el-acelerador-nace-una-de-las-companias-de-viajes-mas-grandes-de-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/realidadturistica.com\/realtur\/"},{"@type":"ListItem","position":2,"name":"La industria tur\u00edstica polaca pisa el acelerador: nace \u00abuna de las compa\u00f1\u00edas de viajes m\u00e1s grandes de Europa\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/realidadturistica.com\/realtur\/#website","url":"https:\/\/realidadturistica.com\/realtur\/","name":"Realidad Tur\u00edstica","description":"","publisher":{"@id":"https:\/\/realidadturistica.com\/realtur\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/realidadturistica.com\/realtur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/realidadturistica.com\/realtur\/#organization","name":"Realidad Tur\u00edstica","alternateName":"Realtur","url":"https:\/\/realidadturistica.com\/realtur\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2021\/12\/logotipo-realidad-turistica.png","width":1382,"height":629,"caption":"Realidad Tur\u00edstica"},"image":{"@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/realidadturistica","https:\/\/www.instagram.com\/realidad_turistica\/"]},{"@type":"Person","@id":"https:\/\/realidadturistica.com\/realtur\/#\/schema\/person\/46aa3c967b83697123b0ca020fb35e7c","name":"Manuel Lorenzo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","url":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","contentUrl":"https:\/\/realidadturistica.com\/realtur\/wp-content\/uploads\/2026\/06\/cropped-manuel-lorenzo-avatar-96x96.jpg","caption":"Manuel Lorenzo"},"description":"El Mtro. Manuel Lorenzo es un experimentado periodista y editor con s\u00f3lida trayectoria en el an\u00e1lisis y difusi\u00f3n de noticias nacionales e internacionales. Destaca su profundo conocimiento sobre el acontecer centroamericano y caribe\u00f1o, y de manera especial en el sector tur\u00edstico de M\u00e9xico. Licenciado en Derecho y Maestro en Estudios Sobre Estados Unidos de Norteam\u00e9rica por la Universidad de las Am\u00e9ricas, Puebla. Cuenta adem\u00e1s con postgrados en el Instituto Mat\u00edas Romero, centro de capacitaci\u00f3n de diplom\u00e1ticos de la Secretar\u00eda de Relaciones Exteriores de M\u00e9xico. Trabaj\u00f3 durante 10 a\u00f1os como corresponsal en la Gu\u00eda Interamericana de Turismo, la gu\u00eda tur\u00edstica m\u00e1s importante de Centroam\u00e9rica. Posteriormente, durante 20 a\u00f1os se desempe\u00f1\u00f3 como Editor Jefe del Peri\u00f3dico Digital Centroamericano y del Caribe, medio especializado en noticias pol\u00edticas, tur\u00edsticas, econ\u00f3micas y de negocios. Desde hace cinco a\u00f1os es Editor Jefe de Realidad Tur\u00edstica, medio digital mexicano especializado en turismo internacional y en particular de Yucat\u00e1n, destacando destinos y noticias del sureste mexicano.","sameAs":["https:\/\/realidadturistica.com\/realtur\/","profile.php?id=61576165411521"],"url":"https:\/\/realidadturistica.com\/realtur\/author\/editor2\/"}]}},"_links":{"self":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/comments?post=8873"}],"version-history":[{"count":1,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8873\/revisions"}],"predecessor-version":[{"id":8875,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/posts\/8873\/revisions\/8875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media\/8874"}],"wp:attachment":[{"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/media?parent=8873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/categories?post=8873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/realidadturistica.com\/realtur\/wp-json\/wp\/v2\/tags?post=8873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}